{"id":72746,"date":"2022-03-02T13:58:46","date_gmt":"2022-03-02T12:58:46","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/economy-work\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/"},"modified":"2022-03-02T13:58:46","modified_gmt":"2022-03-02T12:58:46","slug":"detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica","status":"publish","type":"post","link":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/","title":{"rendered":"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica"},"content":{"rendered":"<p><em>Compartimos el llamamiento del Movimiento Pol\u00edtico por la Unidad para detener la guerra en Ucrania y reabrir un espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica.<\/em><\/p>\n<p>\u00abSi quieres la paz, prepara la paz\u00bb. As\u00ed se expresaba Igino Giordani, un pol\u00edtico pacifista del siglo XX. Solo un cotidiano esfuerzo multiforme por la paz puede<strong> detener la guerra<\/strong> que la historia ya ha declarado demasiadas veces como<strong> una opci\u00f3n absurda<\/strong>.<\/p>\n<p>Los medios de la oposici\u00f3n est\u00e1n desactualizados y abren el camino a una mayor inseguridad, tanto a nivel local como global.<\/p>\n<p>De ello estamos convencidos los pol\u00edticos, funcionarios, ciudadanos, diplom\u00e1ticos del Movimiento Pol\u00edtico por la Unidad, y desde todo el mundo expresamos nuestra cercan\u00eda a los pueblos que sufren esta tr\u00e1gica guerra, mientras apoyamos firmemente a quienes, de diversas maneras, contin\u00faan<strong> negociando por la paz, la \u00fanica soluci\u00f3n verdadera.<\/strong><\/p>\n<p>Nunca es demasiado tarde para reabrir la negociaci\u00f3n y el di\u00e1logo, a corto y largo plazo.<\/p>\n<p>Que la obligaci\u00f3n de la paz nos gu\u00ede.<\/p>\n<p>Identificamos estas tres direcciones principales de compromiso:<\/p>\n<p>1- A menudo la creaci\u00f3n de los estados nacionales no ha sido una elecci\u00f3n libre de los pueblos, sino el resultado de mesas de tratativas de la posguerra, legados de imperialismos. Viejas y nuevas divisiones exigen un esfuerzo pol\u00edtico valiente, que d\u00e9 nuevo significado a las identidades nacionales, que interpele las uniones continentales, en primer lugar a la Uni\u00f3n Europea, m\u00e1s all\u00e1 de los intereses inmediatos.<\/p>\n<p>2- La historia nos ense\u00f1a que las sanciones econ\u00f3micas dejan indemnes a los gobiernos y empobrecen a la sociedad civil, a las mujeres y los hombres, y sobre todo a los ni\u00f1os. Siria es el \u00faltimo y m\u00e1s grave ejemplo de esto.<\/p>\n<p>La elecci\u00f3n de las sanciones ha de llevarse a cabo con cautela, para que no forme parte de la l\u00f3gica de la guerra y de las contraposiciones de fuerza. La pol\u00edtica debe saber controlar los circuitos de las armas y de la industria del carb\u00f3n y solo as\u00ed construir\u00e1 una verdadera paz.<\/p>\n<p>3- Ante el recrudecimiento de las armas nucleares con su potenciaci\u00f3n estrat\u00e9gica, hoy pedimos en voz alta a nuestros gobiernos que se firme e implemente el Tratado sobre la Prohibici\u00f3n de las Armas Nucleares, adoptado solo por 122 Estados el 7 de julio de 2017. La fuerza pol\u00edtica de la ONU debe volver a la acci\u00f3n y la voz de los gobiernos debe integrarse con la voz de las ciudades del planeta, reunidas en una espec\u00edfica asamblea mundial, para darle m\u00e1s fuerza a nuestros pueblos.<\/p>\n<p>En estas horas en que parece prevalecer el poder desnudo de la fuerza, afirmamos sin vacilaci\u00f3n alguna que todav\u00eda y siempre creemos en la construcci\u00f3n de la paz, en los procesos de di\u00e1logo, en los instrumentos de la pol\u00edtica.<\/p>\n<p>Son las organizaciones de la sociedad civil, con la fuerza espiritual y cultural de su fe y con las muchas buenas pr\u00e1cticas las que pondr\u00e1n de relieve los grandes ideales para sostener la historia.<\/p>\n<p>Que nuestros representantes silencien las armas cuanto antes y escuchen a las mujeres y a los hombres de paz.<\/p>\n<p>Mario Bruno, presidente del MPPU<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compartimos el llamamiento del Movimiento Pol\u00edtico por la Unidad para detener la guerra en Ucrania y reabrir un espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica. \u00abSi quieres la paz, prepara la paz\u00bb. As\u00ed se expresaba Igino Giordani, un pol\u00edtico pacifista del siglo XX. Solo un cotidiano esfuerzo multiforme por la paz puede detener la guerra que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":67795,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-72746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica - United World Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica - United World Project\" \/>\n<meta property=\"og:description\" content=\"Compartimos el llamamiento del Movimiento Pol\u00edtico por la Unidad para detener la guerra en Ucrania y reabrir un espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica. \u00abSi quieres la paz, prepara la paz\u00bb. As\u00ed se expresaba Igino Giordani, un pol\u00edtico pacifista del siglo XX. Solo un cotidiano esfuerzo multiforme por la paz puede detener la guerra que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-02T12:58:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Evidenza-appello-pace.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/\"},\"author\":{\"name\":\"anita\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"headline\":\"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica\",\"datePublished\":\"2022-03-02T12:58:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/\"},\"wordCount\":568,\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Foto-Evidenza-appello-pace.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/\",\"name\":\"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Foto-Evidenza-appello-pace.jpg\",\"datePublished\":\"2022-03-02T12:58:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Foto-Evidenza-appello-pace.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Foto-Evidenza-appello-pace.jpg\",\"width\":1200,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\",\"name\":\"anita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"caption\":\"anita\"},\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/author\\\/anita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica - United World Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/","og_locale":"es_ES","og_type":"article","og_title":"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica - United World Project","og_description":"Compartimos el llamamiento del Movimiento Pol\u00edtico por la Unidad para detener la guerra en Ucrania y reabrir un espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica. \u00abSi quieres la paz, prepara la paz\u00bb. As\u00ed se expresaba Igino Giordani, un pol\u00edtico pacifista del siglo XX. Solo un cotidiano esfuerzo multiforme por la paz puede detener la guerra que [&hellip;]","og_url":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/","og_site_name":"United World Project","article_published_time":"2022-03-02T12:58:46+00:00","og_image":[{"width":1200,"height":620,"url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Evidenza-appello-pace.jpg","type":"image\/jpeg"}],"author":"anita","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anita","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/#article","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/"},"author":{"name":"anita","@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"headline":"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica","datePublished":"2022-03-02T12:58:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/"},"wordCount":568,"image":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Evidenza-appello-pace.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/","url":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/","name":"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Evidenza-appello-pace.jpg","datePublished":"2022-03-02T12:58:46+00:00","author":{"@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/#primaryimage","url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Evidenza-appello-pace.jpg","contentUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Evidenza-appello-pace.jpg","width":1200,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/detener-la-guerra-en-ucrania-y-reconstruir-el-espacio-de-dialogo-y-negociacion-politica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/es\/"},{"@type":"ListItem","position":2,"name":"Detener la guerra en Ucrania y reconstruir el espacio de di\u00e1logo y negociaci\u00f3n pol\u00edtica"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/es\/#website","url":"https:\/\/www.unitedworldproject.org\/es\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201","name":"anita","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","caption":"anita"},"url":"https:\/\/www.unitedworldproject.org\/es\/author\/anita\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/72746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/comments?post=72746"}],"version-history":[{"count":0,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/72746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/media\/67795"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/media?parent=72746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/categories?post=72746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/tags?post=72746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}