{"id":72815,"date":"2022-04-12T16:35:17","date_gmt":"2022-04-12T14:35:17","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/economy-work\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/"},"modified":"2022-04-12T16:35:17","modified_gmt":"2022-04-12T14:35:17","slug":"ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis","status":"publish","type":"post","link":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/","title":{"rendered":"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis"},"content":{"rendered":"<h5>de Carlo Cefaloni<\/h5>\n<p>Tres d\u00edas intensos para la delegaci\u00f3n italiana de <em><a href=\"https:\/\/www.stopthewarnow.eu\/#promotori\">Stop the War Now<\/a> <\/em>que lleg\u00f3 a la ciudad de Le\u00f3polis para llevar ayudas, acoger a los pr\u00f3fugos m\u00e1s fr\u00e1giles y abrir caminos para una relaci\u00f3n m\u00e1s estrecha con la sociedad civil ucraniana. Una acci\u00f3n desarmada en un contexto de guerra. Testimonios y cr\u00f3nicas dirigidas por Giulio Boschi de los Focolares en Italia y Alfio Nicotra de Un Puente para\u2026<\/p>\n<p><strong>Destinaci\u00f3n Le\u00f3polis. <\/strong>Ha sido una misi\u00f3n rel\u00e1mpago la que organizaron del 1\u00b0 al 3 de abril con una gran red de asociaciones italianas que llegaron a Ucrania adhiriendo a la propuesta de la Comunidad Papa Juan XXIII (Apg23) para abrir una conexi\u00f3n directa con la poblaci\u00f3n civil que sufre las consecuencias de una guerra con rasgos cada vez m\u00e1s atroces en el coraz\u00f3n del continente europeo.<\/p>\n<p>La acci\u00f3n de la comunidad fundada por el padre Oreste Benzi tiene <strong>sus ra\u00edces en la Operaci\u00f3n Paloma, el cuerpo no violento de paz que naci\u00f3 en los inicios de los a\u00f1os 90<\/strong>, durante la guerra de los Balcanes, cuando un grupo de objetores civiles propuso una campa\u00f1a para ir en desobediencia civil a los Balcanes a apoyar a las v\u00edctimas del conflicto. Voluntarios que luego participaron en la marcha de los 500 que llegaron a Sarajevo sitiada en 1992, como se menciona en la entrevista con Rosa Siciliano de Pax Christi.<\/p>\n<p>Hoy en la ciudad de L&#8217;viv, Lviv, Le\u00f3polis, lejos de la frontera rusa pero a\u00fan afectada por los ataques militares, <strong>la Apg23 \u00abest\u00e1 presente desde los primeros d\u00edas del conflicto para garantizar tranquilidad y ayudar a las personas -especialmente a las m\u00e1s fr\u00e1giles,<\/strong> que se quedan atr\u00e1s y no logran resistir solas- para salir del pa\u00eds, con autobuses y transporte que van a la frontera y luego en Italia, donde les espera una casa para vivir y una familia que los abrace\u00bb.<\/p>\n<p><strong>Los 60 veh\u00edculos que partieron con 220 personas <\/strong>entregaron toneladas de alimentos y medicinas, pero la finalidad de la misi\u00f3n no ha sido solo de car\u00e1cter humanitario, como muchas otras actividades de solidaridad que distinguen una parte de la sociedad italiana.<\/p>\n<p>La intenci\u00f3n es la de promover <strong>una forma de diplomacia comenzando desde abajo por parte de un pueblo de paz<\/strong> que ha tenido la posibilidad de encontrarse con organizaciones de la sociedad civil, as\u00ed como con las autoridades religiosas y civiles de Le\u00f3polis.<\/p>\n<p>Por este motivo <strong>han sido muchas las realidades de diferente proveniencia que han formado parte de esta caravana<\/strong>. Entre ellas tambi\u00e9n la ONG Un Puente por\u2026 especialmente activa en Medio Oriente y en los Balcanes. El copresidente, Alfio Nicotra estuvo en Sarajevo en 1992 y, 30 a\u00f1os despu\u00e9s, se puso de nuevo en viaje para Le\u00f3polis: \u00abEstuve <strong>entre los 500 pacifistas que violaron el cercamiento de Sarajevo y hoy revivo ese esp\u00edritu, ese ser, como padre Tonino Bello nos defini\u00f3: \u201cla ONU de los pueblos\u201d <\/strong>que se opuso a la inercia de la ONU de los poderosos\u00bb.<\/p>\n<p>Este es su testimonio, en esta conexi\u00f3n video grabado apenas regres\u00f3 a casa, para poner en evidencia la necesidad de encontrar todos los caminos para establecer, despu\u00e9s de este viaje, <strong>relaciones directas con la sociedad civil ucraniana que se resiste a la l\u00f3gica de la guerra<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><div class=\"cookieconsent-optout-marketing\">\n                        <a href=\"javascript:Cookiebot.renew()\" style=\"background: url(https:\/\/www.unitedworldproject.org\/wp-content\/plugins\/yt-placeholder-cookiebot\/assets\/placeholder.jpg) no-repeat center center \/ cover; aspect-ratio: 1 \/ 0.48; width: 100%; display: block; margin: 20px 0; position: relative; background-size: cover; background-position: center;\">\n                            <span style=\"position: absolute; bottom: 20px; width: 100%; padding: 0 5%; text-align: center; box-sizing: border-box;\">Para ver este v\u00eddeo, es necesario habilitar todas las cookies<\/span>\n                        <\/a>\n                   <\/div><iframe loading=\"lazy\" title=\"Stop the war now! Dialogo con Alfio Nicotra al ritorno del viaggio a Leopoli\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9blM3RNUjIs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Los ritmos de la caravana italiana eran muy intensos. Partiendo a las 6 am el 1\u00b0 de abril desde Gorizia y llegando a Polonia por la tarde, cerca de la frontera con Ucrania, que atraves\u00f3 a las 6 de la ma\u00f1ana del 2 de abril, para llegar a Le\u00f3polis y volver a salir el domingo 3 de abril.<\/p>\n<p>Aqu\u00ed hay algunos de los audios y videos breves de testimonios directos durante el viaje de <strong>Giulio Boschi, quien junto con Marco Reguzzoni <\/strong>participaron como representantes del <strong>Movimiento de los Focolares<\/strong> saliendo de las ciudades Bolonia y Carpi.<\/p>\n<p><div class=\"cookieconsent-optout-marketing\">\n                        <a href=\"javascript:Cookiebot.renew()\" style=\"background: url(https:\/\/www.unitedworldproject.org\/wp-content\/plugins\/yt-placeholder-cookiebot\/assets\/placeholder.jpg) no-repeat center center \/ cover; aspect-ratio: 1 \/ 0.48; width: 100%; display: block; margin: 20px 0; position: relative; background-size: cover; background-position: center;\">\n                            <span style=\"position: absolute; bottom: 20px; width: 100%; padding: 0 5%; text-align: center; box-sizing: border-box;\">Para ver este v\u00eddeo, es necesario habilitar todas las cookies<\/span>\n                        <\/a>\n                   <\/div><iframe loading=\"lazy\" title=\"Stop the war now! Giulio Boschi verso Leopoli\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/WViEoA4PXYg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><div class=\"cookieconsent-optout-marketing\">\n                        <a href=\"javascript:Cookiebot.renew()\" style=\"background: url(https:\/\/www.unitedworldproject.org\/wp-content\/plugins\/yt-placeholder-cookiebot\/assets\/placeholder.jpg) no-repeat center center \/ cover; aspect-ratio: 1 \/ 0.48; width: 100%; display: block; margin: 20px 0; position: relative; background-size: cover; background-position: center;\">\n                            <span style=\"position: absolute; bottom: 20px; width: 100%; padding: 0 5%; text-align: center; box-sizing: border-box;\">Para ver este v\u00eddeo, es necesario habilitar todas las cookies<\/span>\n                        <\/a>\n                   <\/div><iframe loading=\"lazy\" title=\"Stop the war now! Giulio Boschi in Ucraina\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/GBoprnS1-w0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>A pesar de las alarmas por un ataque a\u00e9reo, la delegaci\u00f3n realiz\u00f3, dentro de la ciudad de Le\u00f3polis, <strong>una marcha con las banderas blancas de una paz cada vez m\u00e1s urgente<\/strong> en un escenario que hace temer un aumento de las tensiones con efectos incontrolables. Dentro de esta contradicci\u00f3n se movi\u00f3 una parte de nuestra sociedad civil, hombres y mujeres que con esta marcha han expresado <strong>la necesidad de no quedarnos como espectadores inertes porque, como dicen, \u00absentimos la necesidad de ponernos en primera persona\u00bb.<\/strong><\/p>\n<p>En la columna de medios con destino a Ucrania, tambi\u00e9n estaba presente el obispo de Bari quien al final envi\u00f3 este mensaje a los participantes de la caravana por la paz. \u00ablos imagino viajando con <strong>un \u201ctesoro\u201d de humanidad que est\u00e1n llamados a custodiar<\/strong>. Gracias por el hermoso testimonio que me han ofrecido en estos espacios de tiempo compartido, que me han enriquecido. Agradezco a Gianpiero y a la Comunidad Papa Juan XXIII y a todos los \u201cvarios\u201d promotores, como el mismo Gianpiero los ha definido.<\/p>\n<p>Pido disculpas si ayer no he participado a la marcha por las calles de Le\u00f3polis, pero hice otra, siempre por las calles de la ciudad, visitando obispos de las otras dos Iglesias, la cat\u00f3lica y ortodoxa rusa, para compartir el mismo don que hicimos al obispo auxiliar de la Iglesia greco-cat\u00f3lica: el man\u00e1 de San Nicol\u00e1s, tomada del cuerpo del santo aqu\u00ed en Bari, fue un momento de gracia y de comuni\u00f3n fraterna.<\/p>\n<p>Buen regreso y\u2026 \u201cque el camino sea siempre en la paz\u201d (saludo samburu- Kenia) Felices pascuas para todos\u00bb.<\/p>\n<p>+padre Giuseppe Satriano<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>de Carlo Cefaloni Tres d\u00edas intensos para la delegaci\u00f3n italiana de Stop the War Now que lleg\u00f3 a la ciudad de Le\u00f3polis para llevar ayudas, acoger a los pr\u00f3fugos m\u00e1s fr\u00e1giles y abrir caminos para una relaci\u00f3n m\u00e1s estrecha con la sociedad civil ucraniana. Una acci\u00f3n desarmada en un contexto de guerra. Testimonios y cr\u00f3nicas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":67841,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-72815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis - United World Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis - United World Project\" \/>\n<meta property=\"og:description\" content=\"de Carlo Cefaloni Tres d\u00edas intensos para la delegaci\u00f3n italiana de Stop the War Now que lleg\u00f3 a la ciudad de Le\u00f3polis para llevar ayudas, acoger a los pr\u00f3fugos m\u00e1s fr\u00e1giles y abrir caminos para una relaci\u00f3n m\u00e1s estrecha con la sociedad civil ucraniana. Una acci\u00f3n desarmada en un contexto de guerra. Testimonios y cr\u00f3nicas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-12T14:35:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Ufficio-stampa-Apg23.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"579\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/\"},\"author\":{\"name\":\"anita\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"headline\":\"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis\",\"datePublished\":\"2022-04-12T14:35:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/\"},\"wordCount\":971,\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Foto-Ufficio-stampa-Apg23.jpeg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/\",\"name\":\"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Foto-Ufficio-stampa-Apg23.jpeg\",\"datePublished\":\"2022-04-12T14:35:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Foto-Ufficio-stampa-Apg23.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Foto-Ufficio-stampa-Apg23.jpeg\",\"width\":1030,\"height\":579,\"caption\":\"Foto Ufficio stampa Apg23\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\",\"name\":\"anita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"caption\":\"anita\"},\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/author\\\/anita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis - United World Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/","og_locale":"es_ES","og_type":"article","og_title":"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis - United World Project","og_description":"de Carlo Cefaloni Tres d\u00edas intensos para la delegaci\u00f3n italiana de Stop the War Now que lleg\u00f3 a la ciudad de Le\u00f3polis para llevar ayudas, acoger a los pr\u00f3fugos m\u00e1s fr\u00e1giles y abrir caminos para una relaci\u00f3n m\u00e1s estrecha con la sociedad civil ucraniana. Una acci\u00f3n desarmada en un contexto de guerra. Testimonios y cr\u00f3nicas [&hellip;]","og_url":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/","og_site_name":"United World Project","article_published_time":"2022-04-12T14:35:17+00:00","og_image":[{"width":1030,"height":579,"url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Ufficio-stampa-Apg23.jpeg","type":"image\/jpeg"}],"author":"anita","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anita","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/#article","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/"},"author":{"name":"anita","@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"headline":"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis","datePublished":"2022-04-12T14:35:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/"},"wordCount":971,"image":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Ufficio-stampa-Apg23.jpeg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/","url":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/","name":"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Ufficio-stampa-Apg23.jpeg","datePublished":"2022-04-12T14:35:17+00:00","author":{"@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/#primaryimage","url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Ufficio-stampa-Apg23.jpeg","contentUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Foto-Ufficio-stampa-Apg23.jpeg","width":1030,"height":579,"caption":"Foto Ufficio stampa Apg23"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/ucrania-desde-italia-una-caravana-de-paz-hasta-leopolis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ucrania, desde Italia una caravana de paz hasta Le\u00f3polis"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/es\/#website","url":"https:\/\/www.unitedworldproject.org\/es\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201","name":"anita","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","caption":"anita"},"url":"https:\/\/www.unitedworldproject.org\/es\/author\/anita\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/72815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/comments?post=72815"}],"version-history":[{"count":0,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/72815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/media\/67841"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/media?parent=72815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/categories?post=72815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/tags?post=72815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}