{"id":73736,"date":"2023-12-15T09:00:23","date_gmt":"2023-12-15T08:00:23","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/economy-work\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/"},"modified":"2023-12-15T09:00:23","modified_gmt":"2023-12-15T08:00:23","slug":"comprender-la-migracion-historias-de-la-ruta-de-los-balcanes","status":"publish","type":"post","link":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/","title":{"rendered":"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes"},"content":{"rendered":"<h5>Por Ana Clara Giovani<\/h5>\n<p>El pasado 7 de diciembre, el webinar \u00abRuta de los Balcanes: situaci\u00f3n de los flujos migratorios en Bosnia\u00bb reuni\u00f3 a personas de diversas organizaciones para sumergirse en una profunda exploraci\u00f3n de los retos migratorios. Esta iniciativa de colaboraci\u00f3n reuni\u00f3 a participantes deseosos de profundizar en su conocimiento y comprensi\u00f3n de los intrincados retos a los que se enfrentan los migrantes a lo largo de la ruta de los Balcanes, concretamente en Bosnia. El acto forma parte del <a href=\"https:\/\/www.new-humanity.org\/en\/project\/heartmony\/\">proyecto HeARTmony<\/a>, cofinanciado por la Uni\u00f3n Europea y alineado a la campa\u00f1a \u00ab<a href=\"https:\/\/www.unitedworldproject.org\/es\/embrace-humanity\/\">Embrace Humanity, Spark Change<\/a>\u00bb 2023-2024 de United World Project.<\/p>\n<p><strong>Embrace Humanity<\/strong>\u00a0(Abrazar la humanidad)<\/p>\n<p>El webinar cont\u00f3 con un elenco de interesantes oradores, cada uno de los cuales aport\u00f3 una perspectiva \u00fanica a la narraci\u00f3n. Emina Hosic, representante del Servicio Jesuita a Refugiados (JRS), inici\u00f3 el di\u00e1logo mostrando la impactante labor del JRS en el acompa\u00f1amiento, servicio y defensa de las personas desplazadas forzosamente. Los esfuerzos de la organizaci\u00f3n abarcan la reconciliaci\u00f3n, la educaci\u00f3n, los medios de subsistencia, la defensa de los derechos y el apoyo psicol\u00f3gico y de salud mental.<\/p>\n<p>A continuaci\u00f3n, Vedran Mihic, del JRS, junto con Emina De\u017emi\u0107, de C\u00e1ritas, profundizaron la situaci\u00f3n de los flujos migratorios en Bosnia. El p\u00fablico pudo comprender mejor los retos a los que se enfrentan las personas de pa\u00edses como Turqu\u00eda, Siria, Rusia y Afganist\u00e1n que buscan asilo. Los ponentes destacaron la realidad de Bosnia, a menudo ignorada, donde los migrantes se enfrentan a criterios estrictos, limitaciones de capacidad y pr\u00e1cticas de expulsi\u00f3n.<\/p>\n<p>A continuaci\u00f3n, Amina Surkovic se centr\u00f3 en la criminalizaci\u00f3n de los inmigrantes y present\u00f3 su investigaci\u00f3n sobre la construcci\u00f3n del miedo y la representaci\u00f3n de los inmigrantes como el \u00abotro criminal\u00bb. A menudo se presenta injustamente a los inmigrantes como delincuentes, construyendo una narrativa que deshumaniza sus figuras y alimenta actitudes prejuiciosas. Su convincente an\u00e1lisis expone las t\u00e1cticas empleadas en la construcci\u00f3n de narrativas, incluidas las afirmaciones falsas, la informaci\u00f3n sesgada, la manipulaci\u00f3n de los hechos, la desinformaci\u00f3n y el sensacionalismo. Al desentra\u00f1ar las complejidades de la influencia de los medios de comunicaci\u00f3n, subray\u00f3 la urgente necesidad de contrarrestar estas narrativas, demostrando que el miedo al otro puede transformarse f\u00e1cilmente en culpabilizaci\u00f3n e instrumentalizaci\u00f3n pol\u00edtica.<\/p>\n<p><strong>Spark Change<\/strong>\u00a0(Provocar el cambio)<\/p>\n<p>Mientras se desarrollaba el webinar, Roberta Niksic, participante del proyecto HeARTmony, comparti\u00f3 los alentadores resultados. El grupo musical <a href=\"https:\/\/www.unitedworldproject.org\/es\/workshop\/heartmony-en-bosnia-con-el-gen-rosso\/\">Gen Rosso organiz\u00f3 talleres y un concierto en Bosnia<\/a>, fomentando conexiones y amistades entre la poblaci\u00f3n local y los inmigrantes. A trav\u00e9s del canto y la danza, los talleres se convirtieron en espacios para el di\u00e1logo, la ruptura de prejuicios y la creaci\u00f3n de un sentimiento de comunidad.<\/p>\n<p>El \u00faltimo segmento del seminario web incluy\u00f3 una din\u00e1mica sesi\u00f3n de preguntas y respuestas, que permiti\u00f3 a los participantes entablar un di\u00e1logo significativo con los ponentes y profundizar en las complejidades de la migraci\u00f3n en los Balcanes.<\/p>\n<p>En un mundo a menudo dividido por las fronteras, este webinar sirve como faro de unidad, animando a las personas a unirse para hacer frente a los retos de la migraci\u00f3n y trabajar por una sociedad m\u00e1s inclusiva y armoniosa. <strong>Marca en tu calendario el<\/strong> <strong>pr\u00f3ximo webinar del 24 de enero<\/strong>, y participa en la conversaci\u00f3n sobre los flujos migratorios en Italia, porque comprender las historias humanas que hay detr\u00e1s de la migraci\u00f3n puede ser un gran paso hacia un cambio positivo.<\/p>\n<p><strong>Aqu\u00ed puedes encontrar un \u00edndice r\u00e1pido de webinar, \u00a1para verlo cuando quieras!<\/strong><\/p>\n<p><a href=\"https:\/\/www.youtube.com\/live\/g6tEA7s1zI8?si=lnyfwVEA2wf0TMkv&amp;t=856\">14:14<\/a>\u00a0\u2013 \u00bfQu\u00e9 es el proyecto HeARTmony?<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/live\/g6tEA7s1zI8?si=kr4i33Gl5PjnyHhC&amp;t=1433\">23:56<\/a>\u00a0\u2013 El Servicio Jesuita a Refugiados (JRS) en acci\u00f3n<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/live\/g6tEA7s1zI8?si=txfqQW6JXZPn2mm9&amp;t=2750\">45:46<\/a>\u00a0\u2013 Situaci\u00f3n de los flujos migratorios en Bosnia<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/live\/g6tEA7s1zI8?si=QpBJjteoCccip44o&amp;t=4524\">1:15:38<\/a>\u00a0\u2013 Investigaci\u00f3n sobre la criminalizaci\u00f3n de los inmigrantes<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/live\/g6tEA7s1zI8?si=Ff74B_ICjhrSrTkp&amp;t=5659\">1:34:05<\/a>\u00a0\u2013 Arte y di\u00e1logo: la experiencia del proyecto HeARTmony a trav\u00e9s de sus participantes<\/p>\n<p><div class=\"cookieconsent-optout-marketing\">\n                        <a href=\"javascript:Cookiebot.renew()\" style=\"background: url(https:\/\/www.unitedworldproject.org\/wp-content\/plugins\/yt-placeholder-cookiebot\/assets\/placeholder.jpg) no-repeat center center \/ cover; aspect-ratio: 1 \/ 0.48; width: 100%; display: block; margin: 20px 0; position: relative; background-size: cover; background-position: center;\">\n                            <span style=\"position: absolute; bottom: 20px; width: 100%; padding: 0 5%; text-align: center; box-sizing: border-box;\">Para ver este v\u00eddeo, es necesario habilitar todas las cookies<\/span>\n                        <\/a>\n                   <\/div><iframe loading=\"lazy\" title=\"Balkan Route - Heartmony project\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/g6tEA7s1zI8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Ana Clara Giovani El pasado 7 de diciembre, el webinar \u00abRuta de los Balcanes: situaci\u00f3n de los flujos migratorios en Bosnia\u00bb reuni\u00f3 a personas de diversas organizaciones para sumergirse en una profunda exploraci\u00f3n de los retos migratorios. Esta iniciativa de colaboraci\u00f3n reuni\u00f3 a participantes deseosos de profundizar en su conocimiento y comprensi\u00f3n de los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":68581,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-73736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comprender la migraci\u00f3n: historias de la ruta de los Balcanes - United World Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes - United World Project\" \/>\n<meta property=\"og:description\" content=\"Por Ana Clara Giovani El pasado 7 de diciembre, el webinar \u00abRuta de los Balcanes: situaci\u00f3n de los flujos migratorios en Bosnia\u00bb reuni\u00f3 a personas de diversas organizaciones para sumergirse en una profunda exploraci\u00f3n de los retos migratorios. Esta iniciativa de colaboraci\u00f3n reuni\u00f3 a participantes deseosos de profundizar en su conocimiento y comprensi\u00f3n de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-15T08:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Balkan-Route-Webinar.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/\"},\"author\":{\"name\":\"anita\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"headline\":\"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes\",\"datePublished\":\"2023-12-15T08:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/\"},\"wordCount\":690,\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Balkan-Route-Webinar.jpeg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/\",\"name\":\"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Balkan-Route-Webinar.jpeg\",\"datePublished\":\"2023-12-15T08:00:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Balkan-Route-Webinar.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Balkan-Route-Webinar.jpeg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/economia-trabajo\\\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\",\"name\":\"anita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"caption\":\"anita\"},\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/author\\\/anita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes - United World Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/","og_locale":"es_ES","og_type":"article","og_title":"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes - United World Project","og_description":"Por Ana Clara Giovani El pasado 7 de diciembre, el webinar \u00abRuta de los Balcanes: situaci\u00f3n de los flujos migratorios en Bosnia\u00bb reuni\u00f3 a personas de diversas organizaciones para sumergirse en una profunda exploraci\u00f3n de los retos migratorios. Esta iniciativa de colaboraci\u00f3n reuni\u00f3 a participantes deseosos de profundizar en su conocimiento y comprensi\u00f3n de los [&hellip;]","og_url":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/","og_site_name":"United World Project","article_published_time":"2023-12-15T08:00:23+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Balkan-Route-Webinar.jpeg","type":"image\/jpeg"}],"author":"anita","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anita","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/#article","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/"},"author":{"name":"anita","@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"headline":"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes","datePublished":"2023-12-15T08:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/"},"wordCount":690,"image":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Balkan-Route-Webinar.jpeg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/","url":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/","name":"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Balkan-Route-Webinar.jpeg","datePublished":"2023-12-15T08:00:23+00:00","author":{"@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/#primaryimage","url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Balkan-Route-Webinar.jpeg","contentUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/Balkan-Route-Webinar.jpeg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/es\/economia-trabajo\/comprender-la-migracion-historias-de-la-ruta-de-los-balcanes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/es\/"},{"@type":"ListItem","position":2,"name":"Comprender la migraci\u00f3n: historias de la ruta de los Balcanes"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/es\/#website","url":"https:\/\/www.unitedworldproject.org\/es\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201","name":"anita","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","caption":"anita"},"url":"https:\/\/www.unitedworldproject.org\/es\/author\/anita\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/73736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/comments?post=73736"}],"version-history":[{"count":0,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/73736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/media\/68581"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/media?parent=73736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/categories?post=73736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/tags?post=73736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}