{"id":78812,"date":"2026-07-24T00:38:04","date_gmt":"2026-07-23T22:38:04","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/?p=78812"},"modified":"2026-07-24T00:55:13","modified_gmt":"2026-07-23T22:55:13","slug":"festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia","status":"publish","type":"post","link":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/","title":{"rendered":"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia"},"content":{"rendered":"<p><em>Un festival de tres d\u00edas convirti\u00f3 a Florencia en la Capital de la Paz. Los lugares elegidos, los temas y las personalidades que participaron hicieron del evento una poderosa invitaci\u00f3n<\/em> a contemplar esas luces ahora inevitables.<\/p>\n<p><a href=\"https:\/\/www.comune.firenze.it\/\">Quien contempla Florencia desde la Bas\u00edlica de San Miniato al Monte<\/a> no puede evitar sentir gratitud por la belleza que ofrece: contemplar la ciudad desde lo alto, desde uno de sus \u00e1ngulos m\u00e1s evocadores, sin pensar en los problemas de tr\u00e1fico, las obras en construcci\u00f3n, la crisis de la vivienda, los problemas del turismo masivo que ahuyenta a la gente, la posible contaminaci\u00f3n o las dificultades en la gesti\u00f3n de residuos; sin tener que enfrentarse a los problemas sociales y humanos de cualquier ciudad. Desde San Miniato al Monte, solo se ve la luz que emana de las ventanas. Los problemas existen, pero es la mirada la que marca la diferencia.<\/p>\n<figure id=\"attachment_78786\" aria-describedby=\"caption-attachment-78786\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-78786\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta3-1024x576.jpeg\" alt=\"Photo_Andrea Gnesutta\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta3-1024x576.jpeg 1024w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta3-300x169.jpeg 300w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta3-768x432.jpeg 768w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta3-1536x864.jpeg 1536w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta3.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-78786\" class=\"wp-caption-text\">Photo_Andrea Gnesutta<\/figcaption><\/figure>\n<h2>Festival Re-Imaginar la Paz: Tres D\u00edas de Di\u00e1logo, Arte y Reconciliaci\u00f3n<\/h2>\n<p>As\u00ed podr\u00edamos resumir la experiencia que la ciudad de Florencia, y simb\u00f3licamente el mundo entero, vivi\u00f3 con el <a href=\"https:\/\/www.reimaginepeacefestival.it\/\">Festival Re-Imaginar la Paz,<\/a> del 10 al 12 de julio: la capital florentina se convirti\u00f3 en un verdadero centro de paz y fraternidad, con un programa de eventos que recorri\u00f3 diversos rincones de la ciudad: desde la Iglesia de San Salvatore al Monte hasta la Badia Fiorentina, desde el Anfiteatro del Parco delle Cascine hasta la Manifattura Tabacchi, desde el Teatro Nazionale hasta la Bas\u00edlica de San Miniato al Monte, que culmin\u00f3 una evocadora marcha interreligiosa por la paz. Lugares emblem\u00e1ticos de la vida social, civil y religiosa de la ciudad se entrelazaron en recorridos f\u00edsicos y humanos para inspirar fraternidad, casi como si se quisiera gritar a todos que, s\u00ed, existen problemas, que las luces no ocultan las sombras y, quiz\u00e1s, incluso las resaltan. Pero es posible caminar juntos entre las sombras para alcanzar una luz que pertenece a todos, que es para todos. Y esa luz se llama paz.<\/p>\n<p>Y as\u00ed, continuaron los conciertos, las pel\u00edculas, los encuentros, los debates, las reflexiones culturales, las actuaciones, los momentos de di\u00e1logo y las experiencias abiertas a la ciudad y al p\u00fablico: una conmovedora fue la de Bushra Awad y Robi Damelin, dos madres \u2014una palestina y otra israel\u00ed\u2014 que perdieron a sus hijos en el conflicto y, desde lo m\u00e1s profundo de su dolor, eligieron un compromiso compartido con la reconciliaci\u00f3n y la paz. O la del empresario israel\u00ed Maoz Inon, quien, junto con el palestino Aziz Abu Sarah, da testimonio de la alternativa al odio.<\/p>\n<figure id=\"attachment_78785\" aria-describedby=\"caption-attachment-78785\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-78785\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta2-1024x576.jpeg\" alt=\"Photo_Andrea Gnesutta\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta2-1024x576.jpeg 1024w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta2-300x169.jpeg 300w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta2-768x432.jpeg 768w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta2-1536x864.jpeg 1536w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta2.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-78785\" class=\"wp-caption-text\">Photo_Andrea Gnesutta<\/figcaption><\/figure>\n<p>Cada momento fue concebido como una oportunidad para escuchar y dialogar, para afirmar que s\u00ed, la paz es posible. Todo ello en presencia de artistas, escritores y cineastas de todo el mundo, en particular israel\u00edes, palestinos e italianos, activistas por la paz y la participaci\u00f3n del Patriarca de Jerusal\u00e9n, el Cardenal Pierbattista Pizzaballa, quien intervino en el gran concierto de clausura el domingo 12 de julio en el Parque Cascine. El cardenal inst\u00f3 a todos a salir \u201cde las narrativas que nos tranquilizan\u201d y a \u201cabrir fronteras y puertas\u201d. La paz es \u201cun ejercicio de la imaginaci\u00f3n, tambi\u00e9n de ver a una persona en el otro\u201d. Ese mismo ejercicio de luz y sombra mencionado anteriormente&#8230;<\/p>\n<h2><span lang=\"ES-CO\">Florencia, una ciudad que elige el di\u00e1logo<\/span><\/h2>\n<p>El proyecto parti\u00f3 de una premisa sencilla: centrarse en la experiencia humana, la escucha activa y la oportunidad de compartir diferentes historias, sensibilidades y perspectivas a trav\u00e9s del arte y la cultura. Florencia ofreci\u00f3 el contexto ideal para este recorrido, al acoger el legado c\u00edvico de figuras como Giorgio La Pira y Mario Primicerio. La inspiraci\u00f3n provino de la artista israel\u00ed Noa, quien, junto con Gil Dor y la artista palestina Mira Awad, dirigi\u00f3 la propuesta art\u00edstica del evento. Fue ella quien pens\u00f3 en Florencia tras conocer al extraordinario alcalde La Pira y constatar c\u00f3mo la ciudad ha sido durante a\u00f1os un centro de colaboraci\u00f3n entre las comunidades religiosas de las tres confesiones monote\u00edstas. L\u00edderes de estas confesiones participaron en los momentos m\u00e1s significativos: desde el arzobispo de la ciudad, monse\u00f1or Gherardo Gambelli, hasta el im\u00e1n de Florencia, Izzedin Elzir, el rabino principal de la comunidad jud\u00eda de Florencia, Gad Fernando Piperno, y el representante de las iglesias cristianas, el pastor Saverio Scuccimarri.<\/p>\n<figure id=\"attachment_78784\" aria-describedby=\"caption-attachment-78784\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-78784\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta1-1024x806.jpeg\" alt=\"Photo_Andrea Gnesutta\" width=\"1024\" height=\"806\" srcset=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta1-1024x806.jpeg 1024w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta1-300x236.jpeg 300w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta1-768x604.jpeg 768w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta1-1536x1209.jpeg 1536w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta1.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-78784\" class=\"wp-caption-text\">Photo_Andrea Gnesutta<\/figcaption><\/figure>\n<p>La Fundaci\u00f3n Giorgio La Pira, la Obra para la Juventud, el Centro Internacional de Estudiantes Giorgio La Pira, el Ayuntamiento de Florencia, la Di\u00f3cesis de Florencia y una diversa red de asociaciones locales que siempre han trabajado por el di\u00e1logo y la paz, han decidido invertir en este esfuerzo de unidad destinado a comprender c\u00f3mo se puede alcanzar la paz juntos o nadie. Y durante estos tres d\u00edas, se ha formulado una primera recomendaci\u00f3n: continuar, en medio de la multitud de problemas existentes que nadie niega, mirando hacia esas luces ahora inevitables.<\/p>\n<figure id=\"attachment_78787\" aria-describedby=\"caption-attachment-78787\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-78787\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta4-1024x751.jpeg\" alt=\"Photo_Andrea Gnesutta\" width=\"1024\" height=\"751\" srcset=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta4-1024x751.jpeg 1024w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta4-300x220.jpeg 300w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta4-768x563.jpeg 768w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta4-1536x1126.jpeg 1536w, https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta4.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-78787\" class=\"wp-caption-text\">Photo_Andrea Gnesutta<\/figcaption><\/figure>\n<p><em>Translated into English by Becca Webley<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un festival de tres d\u00edas convirti\u00f3 a Florencia en la Capital de la Paz. Los lugares elegidos, los temas y las personalidades que participaron hicieron del evento una poderosa invitaci\u00f3n a contemplar esas luces ahora inevitables.<\/p>\n","protected":false},"author":2,"featured_media":78811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[112],"tags":[],"class_list":["post-78812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-compromiso-social"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festival Re-Imaginar la Paz, un himno a la paz desde Florencia - United World Project<\/title>\n<meta name=\"description\" content=\"Un festival de tres d\u00edas convirti\u00f3 a Florencia en la Capital de la Paz. Los lugares elegidos, los temas y las personalidades que participaron hicieron del evento una poderosa invitaci\u00f3n a contemplar esas luces ahora inevitables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia - United World Project\" \/>\n<meta property=\"og:description\" content=\"Un festival de tres d\u00edas convirti\u00f3 a Florencia en la Capital de la Paz. Los lugares elegidos, los temas y las personalidades que participaron hicieron del evento una poderosa invitaci\u00f3n a contemplar esas luces ahora inevitables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-23T22:38:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T22:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta_cover.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/\"},\"author\":{\"name\":\"anita\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"headline\":\"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia\",\"datePublished\":\"2026-07-23T22:38:04+00:00\",\"dateModified\":\"2026-07-23T22:55:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/\"},\"wordCount\":900,\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Photo_Andrea-Gnesutta_cover.jpeg\",\"articleSection\":[\"Arte y Compromiso Social\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/\",\"name\":\"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Photo_Andrea-Gnesutta_cover.jpeg\",\"datePublished\":\"2026-07-23T22:38:04+00:00\",\"dateModified\":\"2026-07-23T22:55:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"description\":\"Un festival de tres d\u00edas convirti\u00f3 a Florencia en la Capital de la Paz. Los lugares elegidos, los temas y las personalidades que participaron hicieron del evento una poderosa invitaci\u00f3n a contemplar esas luces ahora inevitables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Photo_Andrea-Gnesutta_cover.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Photo_Andrea-Gnesutta_cover.jpeg\",\"width\":1920,\"height\":1126,\"caption\":\"Photo_Andrea Gnesutta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/arte-compromiso-social\\\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\",\"name\":\"anita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"caption\":\"anita\"},\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/es\\\/author\\\/anita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia - United World Project","description":"Un festival de tres d\u00edas convirti\u00f3 a Florencia en la Capital de la Paz. Los lugares elegidos, los temas y las personalidades que participaron hicieron del evento una poderosa invitaci\u00f3n a contemplar esas luces ahora inevitables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/","og_locale":"es_ES","og_type":"article","og_title":"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia - United World Project","og_description":"Un festival de tres d\u00edas convirti\u00f3 a Florencia en la Capital de la Paz. Los lugares elegidos, los temas y las personalidades que participaron hicieron del evento una poderosa invitaci\u00f3n a contemplar esas luces ahora inevitables.","og_url":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/","og_site_name":"United World Project","article_published_time":"2026-07-23T22:38:04+00:00","article_modified_time":"2026-07-23T22:55:13+00:00","og_image":[{"width":1920,"height":1126,"url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta_cover.jpeg","type":"image\/jpeg"}],"author":"anita","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anita","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/#article","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/"},"author":{"name":"anita","@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"headline":"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia","datePublished":"2026-07-23T22:38:04+00:00","dateModified":"2026-07-23T22:55:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/"},"wordCount":900,"image":{"@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta_cover.jpeg","articleSection":["Arte y Compromiso Social"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/","url":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/","name":"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta_cover.jpeg","datePublished":"2026-07-23T22:38:04+00:00","dateModified":"2026-07-23T22:55:13+00:00","author":{"@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"description":"Un festival de tres d\u00edas convirti\u00f3 a Florencia en la Capital de la Paz. Los lugares elegidos, los temas y las personalidades que participaron hicieron del evento una poderosa invitaci\u00f3n a contemplar esas luces ahora inevitables.","breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/#primaryimage","url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta_cover.jpeg","contentUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2026\/07\/Photo_Andrea-Gnesutta_cover.jpeg","width":1920,"height":1126,"caption":"Photo_Andrea Gnesutta"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/es\/arte-compromiso-social\/festival-re-imaginar-la-paz-un-himno-a-la-paz-desde-florencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/es\/"},{"@type":"ListItem","position":2,"name":"Festival Re-Imaginar la Paz, un himno a la paz desde Florencia"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/es\/#website","url":"https:\/\/www.unitedworldproject.org\/es\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.unitedworldproject.org\/es\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201","name":"anita","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","caption":"anita"},"url":"https:\/\/www.unitedworldproject.org\/es\/author\/anita\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/78812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/comments?post=78812"}],"version-history":[{"count":2,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/78812\/revisions"}],"predecessor-version":[{"id":78821,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/posts\/78812\/revisions\/78821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/media\/78811"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/media?parent=78812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/categories?post=78812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/es\/wp-json\/wp\/v2\/tags?post=78812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}