{"id":72205,"date":"2021-05-21T14:09:34","date_gmt":"2021-05-21T12:09:34","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/economy-work\/apurimac-au-coeur-de-la-peripherie-2\/"},"modified":"2025-11-26T15:49:04","modified_gmt":"2025-11-26T14:49:04","slug":"apurimac-au-coeur-de-la-peripherie-2","status":"publish","type":"post","link":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/","title":{"rendered":"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie"},"content":{"rendered":"<p><em>Deuxi\u00e8me partie &#8211; les projets au P\u00e9rou<\/em><\/p>\n<p><em>Dans les nombreux villages \u00e9pars dans les Andes du P\u00e9rou vivent des personnes qui, en raison de leur \u00e9loignement de l\u2019h\u00f4pital le plus proche, ont du mal \u00e0 recevoir des soins de sant\u00e9. Toujours au P\u00e9rou, ces derni\u00e8res ann\u00e9es, de tr\u00e8s nombreuses personnes sont arriv\u00e9es du Venezuela, fuyant un pays qui souffre d\u2019une crise d\u00e9sormais intenable. L\u2019ONG Apurimac ETS est aux c\u00f4t\u00e9s de ces personnes, par le biais de deux diff\u00e9rents projets, dont les \u00ab\u00a0p\u00e9riph\u00e9ries\u00a0\u00bb repr\u00e9sentent le centre de leurs activit\u00e9s.\u00a0 <\/em><\/p>\n<p>Apr\u00e8s avoir connu le projet \u00ab\u00a0Tor bell\u2019Infanzia\u00a0\u00bb de Rome (Vous ne l\u2019avez pas encore lu\u00a0? <a href=\"https:\/\/www.unitedworldproject.org\/fr\/workshop\/apurimac-au-coeur-de-la-peripherie\/\">Vous le trouvez ici<\/a>), j\u2019ai contact\u00e9 Chiara, jeune pharmacienne qui travaille chez Apurimac ETS au P\u00e9rou. \u00a0C\u2019est pr\u00e9cis\u00e9ment d\u2019un endroit de ce pays d\u2019Am\u00e9rique latine que l\u2019ONG tire son nom : l\u2019Apurimac est une r\u00e9gion parmi les plus pauvres du P\u00e9rou, situ\u00e9e au sud-est du pays. L\u00e0, il n\u2019y a pas suffisamment de personnel m\u00e9dical pour assurer des soins de sant\u00e9 \u00e0 l\u2019ensemble de la population, en particulier pour des villages situ\u00e9s \u00e0 plus de 8 heures de route de l\u2019h\u00f4pital le plus proche. C\u2019est pourquoi est n\u00e9 en 2018 le projet \u00ab\u00a0Sant\u00e9 et T\u00e9l\u00e9m\u00e9decine\u00a0\u00bb, qui organise des campagnes de sant\u00e9 itin\u00e9rantes dans toute la r\u00e9gion. J\u2019ai demand\u00e9 \u00e0 Chiara de m\u2019expliquer plus pr\u00e9cis\u00e9ment en quoi consistent ces campagnes sanitaires. Je lui laisse la parole\u00a0: elle r\u00e9pond \u00e0 mes questions par le moyen de cette courte vid\u00e9o :<\/p>\n<p><div class=\"cookieconsent-optout-marketing\">\n                        <a href=\"javascript:Cookiebot.renew()\" style=\"background: url(https:\/\/www.unitedworldproject.org\/wp-content\/plugins\/yt-placeholder-cookiebot\/assets\/placeholder.jpg) no-repeat center center \/ cover; aspect-ratio: 1 \/ 0.48; width: 100%; display: block; margin: 20px 0; position: relative; background-size: cover; background-position: center;\">\n                            <span style=\"position: absolute; bottom: 20px; width: 100%; padding: 0 5%; text-align: center; box-sizing: border-box;\">Pour visualiser cette vid\u00e9o, il est n\u00e9cessaire d\u2019activer tous les cookies<\/span>\n                        <\/a>\n                   <\/div><iframe loading=\"lazy\" title=\"APURIMAC: al cuore della periferia\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/5fXF5iWstPc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Comme on peut l\u2019imaginer, en cette p\u00e9riode de pand\u00e9mie, il est devenu impossible de mener les campagnes de sant\u00e9 dont parle Chiara, appel\u00e9es \u00e0 rassembler au m\u00eame endroit un grand nombre de personnes. Mais une r\u00e9ponse efficace pour r\u00e9pondre \u00e0 cette situation a \u00e9t\u00e9 : la t\u00e9l\u00e9m\u00e9decine\u00a0! D\u00e9j\u00e0 exp\u00e9riment\u00e9, puis mis en \u0153uvre bien apr\u00e8s le d\u00e9but de la pand\u00e9mie, l\u2019outil de t\u00e9l\u00e9m\u00e9decine a permis \u00e0 Apurimac ETS de continuer \u00e0 fournir des soins de sant\u00e9 \u00e0 distance. Pour rendre le tout plus efficace, furent confectionn\u00e9s des kits de sant\u00e9 contenant du mat\u00e9riel m\u00e9dical, une t\u00e9l\u00e9 cam\u00e9ra et une tablette. Ceux-ci furent mis \u00e0 la disposition du personnel de sant\u00e9, qui a pu se rendre dans des villages \u00e9loign\u00e9s des grands centres urbains et peu couverts par le syst\u00e8me de sant\u00e9 publique. Tr\u00e8s souvent, dans ces endroits, les gens ne parlent pas l\u2019espagnol, mais le quechua, langue inconnue des m\u00e9decins pr\u00e9sents dans les h\u00f4pitaux. Cela cause de grandes difficult\u00e9s, mais certains travailleurs d\u2019Apurimac ETS connaissent les deux langues et font l\u2019office de m\u00e9diateurs linguistiques et culturels, afin de faciliter la communication. Ce sont ces attentions qui font la diff\u00e9rence et permettent de ne laisser personne en arri\u00e8re.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29467\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_7122-300x200.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/p>\n<p>Chiara m\u2019a mieux expliqu\u00e9 comment, gr\u00e2ce \u00e0 l\u2019utilisation des kits, on tire de grands avantages pour les activit\u00e9s de soins de sant\u00e9 : \u00ab\u00a0la fonction de chaque kit est d\u2019arriver chez le patient. Gr\u00e2ce \u00e0 ce syst\u00e8me, nous parvenons \u00e0 effectuer un suivi complet des signes vitaux de tr\u00e8s nombreuses personnes ; les donn\u00e9es sont re\u00e7ues et analys\u00e9es \u00e0 distance. Le personnel peut ensuite demander des conseils suppl\u00e9mentaires de m\u00e9decins ou de sp\u00e9cialistes aupr\u00e8s de l\u2019\u00e9tablissement de sant\u00e9 concern\u00e9. La t\u00e9l\u00e9m\u00e9decine nous aide ainsi d\u2019arriver, encore aujourd\u2019hui, l\u00e0 o\u00f9 nous apportions auparavant une assistance, au cours de nos campagnes de sant\u00e9.\u00a0\u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29477\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2021-03-04-at-1.56.09-PM-300x225.jpeg\" alt=\"\" width=\"600\" height=\"450\" \/><\/p>\n<p>Un autre aper\u00e7u d\u2019une soci\u00e9t\u00e9 dont Apurimac ETS s\u2019occupe se rencontre chez les migrants v\u00e9n\u00e9zu\u00e9liens\u00a0: il s\u2019agit du projet \u00ab\u00a0Paix et sant\u00e9\u00a0\u00bb, op\u00e9rant dans la ville de Cuzco. Il s\u2019agit d\u2019offrir des soins de sant\u00e9 et de l\u2019assistance juridique \u00e0 des centaines de migrants v\u00e9n\u00e9zu\u00e9liens, qui se sont retrouv\u00e9s au P\u00e9rou ces derniers temps. \u00ab\u00a0C\u2019est un v\u00e9ritable exode\u00a0\u00bb &#8211; dit Chiara, en expliquant la situation actuelle &#8211; \u00ab\u00a0environ 1 million 200 000 migrants sont arriv\u00e9s au P\u00e9rou\u00a0\u00bb. La situation du Venezuela est tr\u00e8s critique : l\u2019ONU a jug\u00e9 cette crise des r\u00e9fugi\u00e9s parmi les plus graves au monde. Selon une \u00e9tude r\u00e9cente du The Economist, 79 % de la population est dans l\u2019extr\u00eame pauvret\u00e9 et 30 % des enfants de moins de 5 ans souffrent de malnutrition chronique ou d\u2019arr\u00eat de croissance. De 2015 \u00e0 aujourd\u2019hui, un sixi\u00e8me des V\u00e9n\u00e9zu\u00e9liens ont fui le pays. Le projet \u00ab\u00a0Paix et sant\u00e9\u00a0\u00bb vise \u00e0 aider ceux qui arrivent au P\u00e9rou dans des conditions d\u00e9sesp\u00e9r\u00e9es, souvent apr\u00e8s des mois de marche. Gr\u00e2ce aux aides financi\u00e8res du minist\u00e8re des Affaires \u00e9trang\u00e8res et de la Coop\u00e9ration internationale, le projet compte \u00e0 ce jour plus de 800 b\u00e9n\u00e9ficiaires. Quant aux questions l\u00e9gales, furent mont\u00e9s des offices d\u2019information, o\u00f9 les migrants peuvent se rendre pour obtenir de l\u2019aide, afin de r\u00e9gulariser leurs documents et s\u2019inscrire \u00e0 l\u2019assurance-maladie nationale. D\u2019un point de vue m\u00e9dical, des soins de sant\u00e9, de base ainsi que sp\u00e9cialis\u00e9s, sont offerts gratuitement au centre de sant\u00e9 \u00ab\u00a0Policlinico Santa Rita\u00a0\u00bb. Chiara me raconte quelques histoires li\u00e9es aux personnes aid\u00e9es par le projet : l\u2019une, en particulier, concerne une grand-m\u00e8re qui, avec sa ni\u00e8ce, a entrepris la fuite du Venezuela pour rejoindre la m\u00e8re de la petite fille, d\u00e9j\u00e0 arriv\u00e9e avant elles au P\u00e9rou. Pendant le voyage, cependant, les difficult\u00e9s, en particulier pour les femmes, sont nombreuses : les deux ont \u00e9t\u00e9 enlev\u00e9es par un groupe de preneurs d\u2019otages qui, apr\u00e8s les avoir s\u00e9par\u00e9es, ont exig\u00e9 de la m\u00e8re, au P\u00e9rou, le paiement d\u2019une ran\u00e7on pour la lib\u00e9ration de sa fille. Ce n\u2019est qu\u2019\u00e0 la suite du paiement que la petite fut lib\u00e9r\u00e9e : \u00a0grand-m\u00e8re et ni\u00e8ce sont ainsi arriv\u00e9es \u00e0 Cuzco. Ils y ont b\u00e9n\u00e9fici\u00e9 d\u2019une aide gr\u00e2ce au projet \u00ab\u00a0Paix et sant\u00e9\u00a0\u00bb : il \u00e9tait essentiel pour elles de pouvoir obtenir, entre autres, une assistance psychologique pour surmonter ce qui, pour les deux, fut un traumatisme majeur.<\/p>\n<p>&nbsp;<\/p>\n<p><div class=\"cookieconsent-optout-marketing\">\n                        <a href=\"javascript:Cookiebot.renew()\" style=\"background: url(https:\/\/www.unitedworldproject.org\/wp-content\/plugins\/yt-placeholder-cookiebot\/assets\/placeholder.jpg) no-repeat center center \/ cover; aspect-ratio: 1 \/ 0.48; width: 100%; display: block; margin: 20px 0; position: relative; background-size: cover; background-position: center;\">\n                            <span style=\"position: absolute; bottom: 20px; width: 100%; padding: 0 5%; text-align: center; box-sizing: border-box;\">Pour visualiser cette vid\u00e9o, il est n\u00e9cessaire d\u2019activer tous les cookies<\/span>\n                        <\/a>\n                   <\/div><iframe loading=\"lazy\" title=\"Pace e salute nella citt\u00e0 di Cuzco\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/SbHZEl5nuxc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Il y a beaucoup d\u2019histoires li\u00e9es \u00e0 ce qu\u2019Apurimac ETS fait pour am\u00e9liorer ces lieux de p\u00e9riph\u00e9rie, physique et sociale. Pour conclure, j\u2019ai demand\u00e9 \u00e0 Chiara si elle avait un message pour tous les jeunes qui conna\u00eetraient ces projets gr\u00e2ce \u00e0 ses r\u00e9cits. Sa r\u00e9ponse fut br\u00e8ve et efficace : \u00ab S\u2019informer et&#8230; se mettre au travail !\u00bb. Elle ajouta : \u00ab\u00a0On voit souvent la r\u00e9alit\u00e9 tout en n\u00e9gatif, mais ce n\u2019est pas toujours le cas. Il y a beaucoup de gens qui travaillent tellement, si dur, faisant leur part pour rendre ce monde meilleur. Renseignez-vous sur ce que vous pouvez faire, et mettez-vous, vous aussi, au travail ! Peut-\u00eatre en commen\u00e7ant par le volontariat&#8230;\u00a0\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-29472\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2316-300x200.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/p>\n<p><strong><em>Quelques informations pratiques : Apurimac ETS lance chaque ann\u00e9e un appel d\u2019offres pour 4 postes de service civil au P\u00e9rou. Plus de d\u00e9tails <a href=\"https:\/\/apurimac.it\/\">sur leur page web<\/a>.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deuxi\u00e8me partie &#8211; les projets au P\u00e9rou Dans les nombreux villages \u00e9pars dans les Andes du P\u00e9rou vivent des personnes qui, en raison de leur \u00e9loignement de l\u2019h\u00f4pital le plus proche, ont du mal \u00e0 recevoir des soins de sant\u00e9. Toujours au P\u00e9rou, ces derni\u00e8res ann\u00e9es, de tr\u00e8s nombreuses personnes sont arriv\u00e9es du Venezuela, fuyant [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":67409,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-72205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie - United World Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie - United World Project\" \/>\n<meta property=\"og:description\" content=\"Deuxi\u00e8me partie &#8211; les projets au P\u00e9rou Dans les nombreux villages \u00e9pars dans les Andes du P\u00e9rou vivent des personnes qui, en raison de leur \u00e9loignement de l\u2019h\u00f4pital le plus proche, ont du mal \u00e0 recevoir des soins de sant\u00e9. Toujours au P\u00e9rou, ces derni\u00e8res ann\u00e9es, de tr\u00e8s nombreuses personnes sont arriv\u00e9es du Venezuela, fuyant [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-21T12:09:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T14:49:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_7172.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"anita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/\"},\"author\":{\"name\":\"anita\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"headline\":\"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie\",\"datePublished\":\"2021-05-21T12:09:34+00:00\",\"dateModified\":\"2025-11-26T14:49:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/\"},\"wordCount\":1262,\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_7172.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/\",\"name\":\"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_7172.jpg\",\"datePublished\":\"2021-05-21T12:09:34+00:00\",\"dateModified\":\"2025-11-26T14:49:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_7172.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_7172.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/economie-travail\\\/apurimac-au-coeur-de-la-peripherie-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\",\"name\":\"anita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"caption\":\"anita\"},\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/fr\\\/author\\\/anita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie - United World Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/","og_locale":"fr_FR","og_type":"article","og_title":"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie - United World Project","og_description":"Deuxi\u00e8me partie &#8211; les projets au P\u00e9rou Dans les nombreux villages \u00e9pars dans les Andes du P\u00e9rou vivent des personnes qui, en raison de leur \u00e9loignement de l\u2019h\u00f4pital le plus proche, ont du mal \u00e0 recevoir des soins de sant\u00e9. Toujours au P\u00e9rou, ces derni\u00e8res ann\u00e9es, de tr\u00e8s nombreuses personnes sont arriv\u00e9es du Venezuela, fuyant [&hellip;]","og_url":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/","og_site_name":"United World Project","article_published_time":"2021-05-21T12:09:34+00:00","article_modified_time":"2025-11-26T14:49:04+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_7172.jpg","type":"image\/jpeg"}],"author":"anita","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"anita","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/#article","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/"},"author":{"name":"anita","@id":"https:\/\/www.unitedworldproject.org\/fr\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"headline":"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie","datePublished":"2021-05-21T12:09:34+00:00","dateModified":"2025-11-26T14:49:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/"},"wordCount":1262,"image":{"@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_7172.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/","url":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/","name":"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_7172.jpg","datePublished":"2021-05-21T12:09:34+00:00","dateModified":"2025-11-26T14:49:04+00:00","author":{"@id":"https:\/\/www.unitedworldproject.org\/fr\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/#primaryimage","url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_7172.jpg","contentUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_7172.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/fr\/economie-travail\/apurimac-au-coeur-de-la-peripherie-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/fr\/"},{"@type":"ListItem","position":2,"name":"APURIMAC: au c\u0153ur de la p\u00e9riph\u00e9rie"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/fr\/#website","url":"https:\/\/www.unitedworldproject.org\/fr\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.unitedworldproject.org\/fr\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201","name":"anita","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","caption":"anita"},"url":"https:\/\/www.unitedworldproject.org\/fr\/author\/anita\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/posts\/72205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/comments?post=72205"}],"version-history":[{"count":1,"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/posts\/72205\/revisions"}],"predecessor-version":[{"id":72206,"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/posts\/72205\/revisions\/72206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/media\/67409"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/media?parent=72205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/categories?post=72205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/fr\/wp-json\/wp\/v2\/tags?post=72205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}