{"id":63985,"date":"2020-06-05T00:46:28","date_gmt":"2020-06-04T22:46:28","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/activity\/casita-estrella-2\/"},"modified":"2025-11-26T09:01:11","modified_gmt":"2025-11-26T08:01:11","slug":"casita-estrella-2","status":"publish","type":"activity","link":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/","title":{"rendered":"Casita Estrella"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18944 size-full\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/logo-casita-estrella.jpg\" alt=\"\" width=\"443\" height=\"124\" \/><\/p>\n<p>Casita Estrella \u00e8 un centro comunitario situato nella zona di El Brete, vicino al quartiere costiero della citt\u00e0 di Paran\u00e1, Entre R\u00edos. Accompagnano bambini, giovani e adulti fornendo loro sostegno scolastico, alfabetizzazione, laboratori commerciali, assistenza sanitaria di base e attivit\u00e0 ricreative. Il suo obiettivo \u00e8 quello di promuovere lo sviluppo della comunit\u00e0, l&#8217;empowerment e la dignit\u00e0 personale generando legami di reciprocit\u00e0.<\/p>\n<p><strong>Website<\/strong><\/p>\n<p><a href=\"https:\/\/www.casitaestrella.org\/\">https:\/\/www.casitaestrella.org\/<\/a><\/p>\n<p><strong>Facebook<\/strong><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/casitaestrella\">https:\/\/www.facebook.com\/casitaestrella<\/a><\/p>\n<p><strong>Contacto<\/strong><\/p>\n<p><a href=\"mailto:cs.casitaestrella@gmail.com\">cs.casitaestrella@gmail.com<\/a><\/p>\n","protected":false},"featured_media":63004,"template":"","meta":{"_acf_changed":false},"activity_topic":[],"activity-type":[],"county":[],"class_list":["post-63985","activity","type-activity","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casita Estrella - United World Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casita Estrella - United World Project\" \/>\n<meta property=\"og:description\" content=\"Casita Estrella \u00e8 un centro comunitario situato nella zona di El Brete, vicino al quartiere costiero della citt\u00e0 di Paran\u00e1, Entre R\u00edos. Accompagnano bambini, giovani e adulti fornendo loro sostegno scolastico, alfabetizzazione, laboratori commerciali, assistenza sanitaria di base e attivit\u00e0 ricreative. Il suo obiettivo \u00e8 quello di promuovere lo sviluppo della comunit\u00e0, l&#8217;empowerment e la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T08:01:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/logo-casita-estrella.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"443\" \/>\n\t<meta property=\"og:image:height\" content=\"124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/activity\\\/casita-estrella-2\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/activity\\\/casita-estrella-2\\\/\",\"name\":\"Casita Estrella - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/activity\\\/casita-estrella-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/activity\\\/casita-estrella-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-casita-estrella.jpg\",\"datePublished\":\"2020-06-04T22:46:28+00:00\",\"dateModified\":\"2025-11-26T08:01:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/activity\\\/casita-estrella-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/activity\\\/casita-estrella-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/activity\\\/casita-estrella-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-casita-estrella.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-casita-estrella.jpg\",\"width\":443,\"height\":124},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/activity\\\/casita-estrella-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casita Estrella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casita Estrella - United World Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/","og_locale":"it_IT","og_type":"article","og_title":"Casita Estrella - United World Project","og_description":"Casita Estrella \u00e8 un centro comunitario situato nella zona di El Brete, vicino al quartiere costiero della citt\u00e0 di Paran\u00e1, Entre R\u00edos. Accompagnano bambini, giovani e adulti fornendo loro sostegno scolastico, alfabetizzazione, laboratori commerciali, assistenza sanitaria di base e attivit\u00e0 ricreative. Il suo obiettivo \u00e8 quello di promuovere lo sviluppo della comunit\u00e0, l&#8217;empowerment e la [&hellip;]","og_url":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/","og_site_name":"United World Project","article_modified_time":"2025-11-26T08:01:11+00:00","og_image":[{"width":443,"height":124,"url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/logo-casita-estrella.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/","url":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/","name":"Casita Estrella - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/logo-casita-estrella.jpg","datePublished":"2020-06-04T22:46:28+00:00","dateModified":"2025-11-26T08:01:11+00:00","breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/#primaryimage","url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/logo-casita-estrella.jpg","contentUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/logo-casita-estrella.jpg","width":443,"height":124},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/it\/activity\/casita-estrella-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/it\/"},{"@type":"ListItem","position":2,"name":"Casita Estrella"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/it\/#website","url":"https:\/\/www.unitedworldproject.org\/it\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/activity\/63985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/activity"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/types\/activity"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/media\/63004"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/media?parent=63985"}],"wp:term":[{"taxonomy":"activity_topic","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/activity_topic?post=63985"},{"taxonomy":"activity-type","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/activity-type?post=63985"},{"taxonomy":"county","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/county?post=63985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}