{"id":69392,"date":"2013-12-29T10:16:12","date_gmt":"2013-12-29T09:16:12","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/economy-work\/gli-angeli-di-barbakeios\/"},"modified":"2013-12-29T10:16:12","modified_gmt":"2013-12-29T09:16:12","slug":"gli-angeli-di-barbakeios","status":"publish","type":"post","link":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/","title":{"rendered":"Gli angeli di Barbakeios"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Le otto donne, soprannominate poi &#8220;gli angeli di Barbakeios&#8221;, <\/strong>inizialmente erano state scambiate per massaie intente a fare spesa per il cenone. Inoltre le donne hanno invitato a chi faceva spesa a prendere dell&#8217;altro e farsi dare poi lo scontrino e a pagare loro il conto.<strong>&nbsp;<\/strong><\/p>\n<p><strong><\/strong><strong>&#8220;Questa scena incredibile<\/strong> \u00e8 andata avanti per quasi un&#8217;ora &#8211; ha dichiarato alla rete tv Ant1 il direttore del mercato -. Almeno 320 persone hanno fatto la spesa grazie alla generosit\u00e0 delle signore in nero e alla fine, secondo i nostri calcoli, hanno regalato circa 16mila euro di carne&#8221;.<\/p>\n<p><strong>Fonte:&nbsp;<a href=\"http:\/\/www.repubblica.it\/\">www.repubblica.it<\/a><\/strong>&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p><p><em>Otto donne vestite di nero hanno pagato la spesa a chi non poteva permetterselo al mercato di Atene.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"images\/news\/2013-2015\/Barbakeios.jpg\" width=\"230\" height=\"150\" alt=\"Barbakeios\" style=\"float: left; margin-top: 5px; margin-right: 5px;\" \/><strong>E&#8217; stata raccontata<\/strong> dal quotidiano &#8220;La Repubblica&#8221; nei giorni di &nbsp;Natale. Ha fatto &nbsp;il giro del web. Ha dato speranza. E&#8217; la storia che viene dalla Grecia messa in ginocchio dalla crisi economica. &nbsp;<\/p>\n<p><strong>Il 22 dicembre al popolare mercato di Atene<\/strong>, Barbakeios, dove &nbsp;si vendono ogni tipo di prodotto alimentare otto donne, vestite di nero, si sono messe vicino alle casse di un negozio pagando la spesa a coloro che avevano piccole porzioni di carne.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-69392","post","type-post","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli angeli di Barbakeios - United World Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli angeli di Barbakeios - United World Project\" \/>\n<meta property=\"og:description\" content=\"Otto donne vestite di nero hanno pagato la spesa a chi non poteva permetterselo al mercato di Atene. E&#039; stata raccontata dal quotidiano &quot;La Repubblica&quot; nei giorni di &nbsp;Natale. Ha fatto &nbsp;il giro del web. Ha dato speranza. E&#039; la storia che viene dalla Grecia messa in ginocchio dalla crisi economica. &nbsp; Il 22 dicembre al popolare mercato di Atene, Barbakeios, dove &nbsp;si vendono ogni tipo di prodotto alimentare otto donne, vestite di nero, si sono messe vicino alle casse di un negozio pagando la spesa a coloro che avevano piccole porzioni di carne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-29T09:16:12+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/gli-angeli-di-barbakeios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/gli-angeli-di-barbakeios\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#\\\/schema\\\/person\\\/eb42d6478d5877ce01b2709e619bc2bd\"},\"headline\":\"Gli angeli di Barbakeios\",\"datePublished\":\"2013-12-29T09:16:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/gli-angeli-di-barbakeios\\\/\"},\"wordCount\":107,\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/gli-angeli-di-barbakeios\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/gli-angeli-di-barbakeios\\\/\",\"name\":\"Gli angeli di Barbakeios - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#website\"},\"datePublished\":\"2013-12-29T09:16:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#\\\/schema\\\/person\\\/eb42d6478d5877ce01b2709e619bc2bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/gli-angeli-di-barbakeios\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/gli-angeli-di-barbakeios\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/gli-angeli-di-barbakeios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gli angeli di Barbakeios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#\\\/schema\\\/person\\\/eb42d6478d5877ce01b2709e619bc2bd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.unitedworldproject.org\"],\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli angeli di Barbakeios - United World Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/","og_locale":"it_IT","og_type":"article","og_title":"Gli angeli di Barbakeios - United World Project","og_description":"Otto donne vestite di nero hanno pagato la spesa a chi non poteva permetterselo al mercato di Atene. E' stata raccontata dal quotidiano \"La Repubblica\" nei giorni di &nbsp;Natale. Ha fatto &nbsp;il giro del web. Ha dato speranza. E' la storia che viene dalla Grecia messa in ginocchio dalla crisi economica. &nbsp; Il 22 dicembre al popolare mercato di Atene, Barbakeios, dove &nbsp;si vendono ogni tipo di prodotto alimentare otto donne, vestite di nero, si sono messe vicino alle casse di un negozio pagando la spesa a coloro che avevano piccole porzioni di carne.","og_url":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/","og_site_name":"United World Project","article_published_time":"2013-12-29T09:16:12+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/#article","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/"},"author":{"name":"admin","@id":"https:\/\/www.unitedworldproject.org\/it\/#\/schema\/person\/eb42d6478d5877ce01b2709e619bc2bd"},"headline":"Gli angeli di Barbakeios","datePublished":"2013-12-29T09:16:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/"},"wordCount":107,"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/","url":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/","name":"Gli angeli di Barbakeios - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/it\/#website"},"datePublished":"2013-12-29T09:16:12+00:00","author":{"@id":"https:\/\/www.unitedworldproject.org\/it\/#\/schema\/person\/eb42d6478d5877ce01b2709e619bc2bd"},"breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/gli-angeli-di-barbakeios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/it\/"},{"@type":"ListItem","position":2,"name":"Gli angeli di Barbakeios"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/it\/#website","url":"https:\/\/www.unitedworldproject.org\/it\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.unitedworldproject.org\/it\/#\/schema\/person\/eb42d6478d5877ce01b2709e619bc2bd","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf7f95f857c4a56753bee99a58a90ea6c495b7c5364cc812ff43a6d8f153f574?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.unitedworldproject.org"],"url":"https:\/\/www.unitedworldproject.org\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/posts\/69392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/comments?post=69392"}],"version-history":[{"count":0,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/posts\/69392\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/media?parent=69392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/categories?post=69392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/tags?post=69392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}