{"id":74382,"date":"2025-06-08T07:00:28","date_gmt":"2025-06-08T05:00:28","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/economy-work\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/"},"modified":"2025-11-26T16:26:14","modified_gmt":"2025-11-26T15:26:14","slug":"la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2","status":"publish","type":"post","link":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/","title":{"rendered":"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough"},"content":{"rendered":"<p>Risplende la grande bellezza degli <strong>oceani,<\/strong> nel nuovo film di Sir <strong>David Attenborough<\/strong>, disponibile a livello globale dall&#8217;8 giugno (Giornata mondiale degli Oceani) su National Geographic, visibile attraverso la piattaforma Disney+. Diretto da Toby Nowlan, Keith Scholey e Colin Butfield, si intitola <strong><em>Il segreto dell&#8217;oceano<\/em><\/strong> con David Attenborough, e c\u2019\u00e8 dentro la maestosit\u00e0 e la forza spettacolare degli oceani.<\/p>\n<p>La voce corposa del maestro inglese, <strong>novantanovenne<\/strong> ancora straordinario divulgatore, \u00e8 sostenuta da una musica incalzante ed \u00e8 intervallata da testimonianze interessanti. Si distende sopra il gioco di acqua e luce, di limpidezza e colori magnifici, ma non \u00e8 solo meraviglia quella che pulsa sotto l&#8217;immenso orizzonte azzurro del documentario. <strong>\u00c8 anche complessit\u00e0. Drammaticit\u00e0. Dolorosa violenza. \u00c8 necessit\u00e0 urgente di provvedere alla salute dei grandi mari in tutto il mondo.<\/strong><\/p>\n<figure id=\"attachment_58263\" aria-describedby=\"caption-attachment-58263\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-58263\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_027-1-Large.jpeg\" alt=\"A clown anemonefish on a coral reef in Raja Ampat, Indonesia. (Credit: Olly Scholey)\" width=\"1280\" height=\"854\" \/><figcaption id=\"caption-attachment-58263\" class=\"wp-caption-text\">A clown anemonefish on a coral reef in Raja Ampat, Indonesia. (Credit: Olly Scholey)<\/figcaption><\/figure>\n<h2>David Attenborough mostra le ferite degli Oceani<\/h2>\n<p>Prodotto da Silverback Films e Open Planet Studios, <em>Il segreto dell\u2019Oceano<\/em> (prima collaborazione tra National Geographic e David Attenborough) \u00e8 basato su un\u2019approfondita ricerca scientifica marina e sul supporto di consulenti scientifici, tra cui il National Geographic Pristine Seas founder, Enric Sala.<\/p>\n<p>Attingendo alla sua vita di straordinario esploratore (anche marino), Attenborough ci accompagna alla meravigliosa scoperta di habitat sottomarini spettacolari, con ecosistemi sorprendentemente diversi: <strong>giungle di alghe giganti, barriere coralline e montagne nel cuore dell\u2019oceano.<\/strong><\/p>\n<p>Ma il racconto mostra anche le ferite dello sbiancamento dei coralli, della pesca intensiva e industriale, a strascico o dragaggio, della mancanza di cura per le forme di vita animali e vegetali subacquee. Parla di <strong>sfruttamento feroce del mare<\/strong> che danneggia in primis, come in ogni crisi ambientale, i gruppi e le classi sociali pi\u00f9 svantaggiate. Lo mostrano le immagini delle reti vuote, riempite pi\u00f9 di plastica che di pesce, dei pescatori della Liberia. Perch\u00e9 tutto \u00e8 strettamente connesso, ci ricorda Attenborough, ed \u00e8 fondamentale per evitare la catastrofe climatica. <strong>&#8220;Se salvi il mare, salvi il mondo&#8221;<\/strong>, dice alla fine del film, e quella salvaguardia riguarda ogni essere umano.<\/p>\n<figure id=\"attachment_58273\" aria-describedby=\"caption-attachment-58273\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-58273\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_056-Large.jpeg\" alt=\"A bait ball in the open ocean near Azores. (Credit: Silverback Films and Open Planet Studios\/Doug Anderson)\" width=\"1280\" height=\"720\" \/><figcaption id=\"caption-attachment-58273\" class=\"wp-caption-text\">A bait ball in the open ocean near Azores. (Credit: Silverback Films and Open Planet Studios\/Doug Anderson)<\/figcaption><\/figure>\n<h2>Attenborough scuote le coscienze del grande pubblico<\/h2>\n<p>Ci sono le delicate sfide che gli oceani debbono affrontare, dunque, in questo spettacolare, scientifico e insieme umano, documentario. C&#8217;\u00e8 l\u2019esortazione a comprendere meglio il loro prezioso contributo alla salvezza al mondo.<\/p>\n<p>Il grande pubblico viene informato e invitato a <strong>osservare le ferite ma anche le possibili soluzioni<\/strong> per ripristinare l&#8217;antico splendore oceanico, funzionale alla stabilizzazione del clima e al benessere del mondo intero, perch\u00e9 tutto \u00e8 in relazione, ribadisce il lavoro del grande storico naturale di fama mondiale.<\/p>\n<p>Si riflette sugli esiti di certo progresso ormai visibilmente nocivi, ma anche sulla <strong>nuova scienza capace di dare futuro nella vita del mare, che significa sempre vita oltre il mare.<\/strong><\/p>\n<p>Da una parte, lo studioso espone le grandi minacce per la salute degli oceani, dall&#8217;altra ci ricorda che agendo ora \u00e8 possibile recuperare la vita marina su una scala senza precedenti. Anche perch\u00e9 <strong>gli oceani hanno un\u2019incredibile resilienza e capacit\u00e0 di recupero, se protetti.<\/strong><\/p>\n<figure id=\"attachment_58268\" aria-describedby=\"caption-attachment-58268\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-58268\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_050-Large.jpeg\" alt=\"A humpback whale breaches. (Credit: Silverback Films and Open Planet Studios\/Steve Benjamin)\" width=\"1280\" height=\"853\" \/><figcaption id=\"caption-attachment-58268\" class=\"wp-caption-text\">A humpback whale breaches. (Credit: Silverback Films and Open Planet Studios\/Steve Benjamin)<\/figcaption><\/figure>\n<h2>David Attenborough mostra la speranza per gli oceani<\/h2>\n<p>Di ferite e speranza, di abissi e raggi di luce, parla <em>Il segreto dell\u2019Oceano<\/em>, ricordandoci che inevitabilmente si passa per il nostro lavoro, perch\u00e9 se \u00e8 vero &#8220;gli oceani hanno il potere di proteggere&#8221; e &#8220;danno vita&#8221; (dice una delle testimonianze) \u00e8 vero anche che tutto passa per il nostro comportamento.<\/p>\n<p>Siamo in un tempo di grandi scoperte scientifiche che offrono la possibilit\u00e0 di studiare gli Oceani come mai si era fatto prima, e queste scoperte ci parlano dello straordinario strumento delle riserve marine.<\/p>\n<p><strong>&#8220;La mia vita ha coinciso con la grande era delle scoperte oceaniche<\/strong> \u2013 dice lo stesso Attenborough &#8211; negli ultimi cento anni, gli scienziati e gli esploratori hanno rivelato nuove specie straordinarie, migrazioni epiche ed ecosistemi complessi e sorprendenti. In questo documentario condividiamo queste meravigliose scoperte, scopriamo perch\u00e9 il nostro oceano \u00e8 in condizioni di salute cos\u00ec precarie e, cosa forse pi\u00f9 importante, mostriamo come pu\u00f2 tornare a vivere&#8221;.<\/p>\n<p>Nel finale, appare questa didascalia: &#8220;Il film \u00e8 uscito nel 2025, a met\u00e0 del decennio oceanico delle Nazioni Unite e ad oggi, quasi tutti i paesi si sono impegnati a proteggere completamente il 30% delle proprie acque entro il 2030. Ora, la responsabilit\u00e0 di garantire che ci\u00f2 accada ricade su tutti noi&#8221;.<\/p>\n<p>Leggiamo nel pressbook che gli educatori possono essere parte della soluzione, parlando de i segreti dell\u2019oceano con David Attenborough nelle classi e ispirando i giovani, futuri custodi degli oceani. Nel corso di quest\u2019anno, il National Geographic Pristine Seas metter\u00e0 il film documentario a disposizione degli educatori di scuole, universit\u00e0, musei e biblioteche, e per conferenze ed eventi educativi e di beneficenza a scopo non commerciale. Per saperne di pi\u00f9, <a href=\"https:\/\/www.nationalgeographic.org\/society\/ocean-with-david-attenborough\/\">qui.<\/a><\/p>\n<figure id=\"attachment_58258\" aria-describedby=\"caption-attachment-58258\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-58258\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_012-Large.jpeg\" alt=\"A compass jellyfish off the coast of Pembrokeshire, United Kingdom. (Credit: Olly Scholey)\" width=\"1280\" height=\"853\" \/><figcaption id=\"caption-attachment-58258\" class=\"wp-caption-text\">A compass jellyfish off the coast of Pembrokeshire, United Kingdom. (Credit: Olly Scholey)<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Risplende la grande bellezza degli oceani, nel nuovo film di Sir David Attenborough, disponibile a livello globale dall&#8217;8 giugno \u2013 Giornata mondiale degli oceani &#8211; su National Geographic, visibile attraverso la piattaforma Disney+.<\/p>\n","protected":false},"author":2,"featured_media":69018,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-74382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough - United World Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough - United World Project\" \/>\n<meta property=\"og:description\" content=\"Risplende la grande bellezza degli oceani, nel nuovo film di Sir David Attenborough, disponibile a livello globale dall&#039;8 giugno \u2013 Giornata mondiale degli oceani - su National Geographic, visibile attraverso la piattaforma Disney+.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-08T05:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T15:26:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_057-Large.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"anita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/\"},\"author\":{\"name\":\"anita\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"headline\":\"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough\",\"datePublished\":\"2025-06-08T05:00:28+00:00\",\"dateModified\":\"2025-11-26T15:26:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/\"},\"wordCount\":859,\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/OceanWithDavidAttenborough_057-Large.jpeg\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/\",\"name\":\"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/OceanWithDavidAttenborough_057-Large.jpeg\",\"datePublished\":\"2025-06-08T05:00:28+00:00\",\"dateModified\":\"2025-11-26T15:26:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/OceanWithDavidAttenborough_057-Large.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/OceanWithDavidAttenborough_057-Large.jpeg\",\"width\":1280,\"height\":853,\"caption\":\"David Attenborough stands at the coast in Southern England. (Credit: Silverback Films and Open Planet Studios\\\/Keith Scholey)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/economia-e-lavoro\\\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\",\"name\":\"anita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"caption\":\"anita\"},\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/it\\\/author\\\/anita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough - United World Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/","og_locale":"it_IT","og_type":"article","og_title":"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough - United World Project","og_description":"Risplende la grande bellezza degli oceani, nel nuovo film di Sir David Attenborough, disponibile a livello globale dall'8 giugno \u2013 Giornata mondiale degli oceani - su National Geographic, visibile attraverso la piattaforma Disney+.","og_url":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/","og_site_name":"United World Project","article_published_time":"2025-06-08T05:00:28+00:00","article_modified_time":"2025-11-26T15:26:14+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_057-Large.jpeg","type":"image\/jpeg"}],"author":"anita","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"anita","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/#article","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/"},"author":{"name":"anita","@id":"https:\/\/www.unitedworldproject.org\/it\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"headline":"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough","datePublished":"2025-06-08T05:00:28+00:00","dateModified":"2025-11-26T15:26:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/"},"wordCount":859,"image":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_057-Large.jpeg","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/","url":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/","name":"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_057-Large.jpeg","datePublished":"2025-06-08T05:00:28+00:00","dateModified":"2025-11-26T15:26:14+00:00","author":{"@id":"https:\/\/www.unitedworldproject.org\/it\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/#primaryimage","url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_057-Large.jpeg","contentUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/OceanWithDavidAttenborough_057-Large.jpeg","width":1280,"height":853,"caption":"David Attenborough stands at the coast in Southern England. (Credit: Silverback Films and Open Planet Studios\/Keith Scholey)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/it\/economia-e-lavoro\/la-bellezza-le-ferite-e-la-forza-degli-oceani-nel-nuovo-documentario-di-david-attenborough-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/it\/"},{"@type":"ListItem","position":2,"name":"La bellezza, le ferite e la forza degli oceani, nel nuovo documentario di David Attenborough"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/it\/#website","url":"https:\/\/www.unitedworldproject.org\/it\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.unitedworldproject.org\/it\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201","name":"anita","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","caption":"anita"},"url":"https:\/\/www.unitedworldproject.org\/it\/author\/anita\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/posts\/74382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/comments?post=74382"}],"version-history":[{"count":1,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/posts\/74382\/revisions"}],"predecessor-version":[{"id":74383,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/posts\/74382\/revisions\/74383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/media\/69018"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/media?parent=74382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/categories?post=74382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/it\/wp-json\/wp\/v2\/tags?post=74382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}