{"id":73050,"date":"2022-10-04T13:38:21","date_gmt":"2022-10-04T11:38:21","guid":{"rendered":"https:\/\/www.unitedworldproject.org\/economy-work\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/"},"modified":"2025-11-26T16:13:35","modified_gmt":"2025-11-26T15:13:35","slug":"papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia","status":"publish","type":"post","link":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/","title":{"rendered":"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d"},"content":{"rendered":"<h5><strong>Por Lucia Capuzzi<\/strong><\/h5>\n<p><em>Em 24 de setembro de 2022, o Papa Francisco foi a Assis para se encontrar com os jovens economistas, empres\u00e1rios e agentes de transforma\u00e7\u00e3o da Economia de Francesco, que vieram de mais de 100 pa\u00edses ao redor do mundo para a terceira edi\u00e7\u00e3o do evento, a primeira presencial.<\/em><\/p>\n<p>Paz, cuidado, servi\u00e7o, prote\u00e7\u00e3o, amizade, alian\u00e7a, reconhecimento, dignidade, partilha, felicidade. Estas s\u00e3o as dez palavras da economia da vida que os jovens economistas, empres\u00e1rios, agentes de transforma\u00e7\u00e3o decidiram incorporar na realidade, a convite do Papa Francisco.<\/p>\n<p>N\u00e3o \u00e9 uma utopia, &#8220;porque j\u00e1 a estamos construindo&#8221;, conclui o \u201cPacto\u201d assinado em 24 de setembro no teatro Lirick, em Assis, por <strong>Lilly Ralyn Satidtanasarn<\/strong>, de 14 anos, em nome de todos os participantes da <strong>Economia de Francisco (EoF)<\/strong> e do pr\u00f3prio <strong>Papa Francisco<\/strong>.<\/p>\n<p>Uma adolescente tailandesa e o bispo de Roma s\u00e3o os guardi\u00f5es dessa \u201cjarra do futuro\u201d. Uma \u00e2nfora de papel e tinta na qual os jovens e as jovens recolheram seus compromissos pessoais, que nasceram e amadureceram em tr\u00eas anos de sess\u00f5es de trabalho online.<\/p>\n<figure id=\"attachment_39191\" aria-describedby=\"caption-attachment-39191\" style=\"width: 1800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39191\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2155-2048x1365-1.jpg\" alt=\"\" width=\"1800\" height=\"1200\" \/><figcaption id=\"caption-attachment-39191\" class=\"wp-caption-text\">Fonte: Diocesi Assisi<\/figcaption><\/figure>\n<p>\u201cCom o texto do Pacto, vamos confiar voc\u00eas \u00e0 terra como as ra\u00edzes da economia de amanh\u00e3, no jardim de rosas da Porziuncola, de onde os filhos de Francisco partiram para o mundo\u201d, disse <strong>Lourdes<\/strong>, uma dos tr\u00eas apresentadores que se revezaram no palco, no qual havia cerca de trinta jovens, incluindo oito testemunhas. Sonhadores com os p\u00e9s firmemente plantados no ch\u00e3o, capazes de revolucionar o mundo com \u201co amor, com a engenhosidade e com as m\u00e3os\u201d.<\/p>\n<p>Como <strong>Facundo Pascutto<\/strong>, argentino de Lomas de Zamora, uma enorme cidade sat\u00e9lite de Buenos Aires que, com a Faculdade de Ci\u00eancias Sociais, transforma associa\u00e7\u00f5es de bairro, sindicatos, universidades, cooperativas, cantinas comunit\u00e1rias, unidades penitenci\u00e1rias e empresas em \u201cpequenas Assis\u201d, ou seja, espa\u00e7os de encontro entre os diversos atores sociais.<\/p>\n<p>Ou <strong>Henry Totin<\/strong>, do Benin, que, com a associa\u00e7\u00e3o Javev, fez de uma planta parasita \u2013 o jacinto d&#8217;\u00e1gua ou togbl\u00e9 \u2013 um recurso econ\u00f4mico para os agricultores do vale de Ou\u00e9m\u00e9. Ou <strong>Maryam<\/strong>, uma ativista dos direitos das mulheres, que fugiu do Afeganist\u00e3o do Talib\u00e3 gra\u00e7as \u00e0 rede de contatos ativados pela Economia de Francisco.<\/p>\n<p>\u00c9 imposs\u00edvel resumir o caleidosc\u00f3pio de hist\u00f3rias e hist\u00f3ria em que se baseiam os doze pontos do Pacto. Alguns muito novos, como \u201ca Fazenda de Francisco\u201d, inventada por <strong>Mateusz Ciasnocha<\/strong>, um fazendeiro do norte da Pol\u00f4nia, que durante o processo desencadeado pelo Papa encontrou uma maneira de combinar agricultura e justi\u00e7a. \u201cComo? Respeitando os campos e aqueles que trabalham neles. Agora criamos uma nova empresa na Nig\u00e9ria para apoiar a produ\u00e7\u00e3o familiar de cinco aldeias na regi\u00e3o de Ibadan\u201d, disse ele. Outras hist\u00f3rias, no entanto, s\u00e3o antigas. A Comunidade da Paz de S\u00e3o Jos\u00e9 de Apartad\u00f3 tem 25 anos. \u201cFoi fundada em 23 de mar\u00e7o de 1997, quando ningu\u00e9m falava de economia circular e agricultura sustent\u00e1vel. Tamb\u00e9m n\u00e3o sab\u00edamos muito sobre isso. Tudo aconteceu por \u201cchiripa\u2019\u201d.<\/p>\n<p><strong>Jos\u00e9 Roviro<\/strong> repetiu essa palavra v\u00e1rias vezes. \u201cSignifica &#8216;sorte&#8217; ou &#8216;provid\u00eancia&#8217;\u201d, explica. Composta por um grupo de camponeses deslocados pelo conflito colombiano, a Comunidade optou por dizer n\u00e3o \u00e0 viol\u00eancia. \u201cComo t\u00ednhamos experimentado isso em nossa pele \u2013 acrescentou <strong>Sayda Arteaga<\/strong> \u2013, decidimos n\u00e3o a infligir aos outros\u201d.<\/p>\n<p>Agora, a iniciativa \u2013 apoiada pela Opera\u00e7\u00e3o colomba \u2013 produz alimentos sustent\u00e1veis gra\u00e7as a um sistema de trabalho comum. A partir do modelo pioneiro, ent\u00e3o, outros caminhos despontam. \u201cA rec\u00e9m-nascida Funda\u00e7\u00e3o Rut iniciar\u00e1 a partir da Comunidade o processo de escuta, para desenvolver uma grande plataforma digital (Inter Zona) sobre viola\u00e7\u00f5es de direitos humanos e formas de resist\u00eancia n\u00e3o violenta\u201d, destacaram <strong>Annamaria De Paola<\/strong> e <strong>Giovanna Martelli<\/strong>.<\/p>\n<p>Pequenos e grandes exemplos de outra poss\u00edvel economia em que os jovens da Eof acreditam e, alguns deles, \u201cem manh\u00e3s particularmente brilhantes, j\u00e1 vislumbraram o in\u00edcio da terra prometida\u201d. Quanto tempo levar\u00e1 para alcan\u00e7\u00e1-la? Muito, argumentam c\u00e9ticos, em geral n\u00e3o desinteressados realmente. O povo da Eof n\u00e3o se importa e agora prossegue o caminho com a abertura da Economia de Francesco 2.0. Nisso eles s\u00e3o prof\u00e9ticos: movem-se na noite, como a sentinela da passagem de Isa\u00edas. Eles n\u00e3o t\u00eam respostas para os transeuntes angustiados que perguntam quanto falta para o raiar da aurora, no entanto os escutam. S\u00e3o mulheres e homens do di\u00e1logo noturno. Porque \u2013 ressoou fortemente ontem do palco de Assis \u2013 \u201cn\u00e3o h\u00e1 amanhecer mais lindo do que aquele que nos surpreende na companhia dos profetas\u201d.<\/p>\n<figure id=\"attachment_39186\" aria-describedby=\"caption-attachment-39186\" style=\"width: 1800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39186\" src=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2125-2048x1365-1.jpg\" alt=\"\" width=\"1800\" height=\"1200\" \/><figcaption id=\"caption-attachment-39186\" class=\"wp-caption-text\">Fonte: Diocesi Assisi<\/figcaption><\/figure>\n<p>Fonte: <a href=\"https:\/\/www.avvenire.it\/papa\/pagine\/papa-francesco-ad-assisi\">https:\/\/www.avvenire.it\/papa\/pagine\/papa-francesco-ad-assisi<\/a><\/p>\n<p>LEIA O TEXTO COMPLETO DO PACTO: <a href=\"https:\/\/francescoeconomy.org\/it\/il-patto-per-leconomia-di-papa-francesco-con-i-giovani-2\/\">https:\/\/francescoeconomy.org\/it\/il-patto-per-leconomia-di-papa-francesco-con-i-giovani-2\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Lucia Capuzzi Em 24 de setembro de 2022, o Papa Francisco foi a Assis para se encontrar com os jovens economistas, empres\u00e1rios e agentes de transforma\u00e7\u00e3o da Economia de Francesco, que vieram de mais de 100 pa\u00edses ao redor do mundo para a terceira edi\u00e7\u00e3o do evento, a primeira presencial. Paz, cuidado, servi\u00e7o, prote\u00e7\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":68070,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-73050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d - United World Project<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d - United World Project\" \/>\n<meta property=\"og:description\" content=\"Por Lucia Capuzzi Em 24 de setembro de 2022, o Papa Francisco foi a Assis para se encontrar com os jovens economistas, empres\u00e1rios e agentes de transforma\u00e7\u00e3o da Economia de Francesco, que vieram de mais de 100 pa\u00edses ao redor do mundo para a terceira edi\u00e7\u00e3o do evento, a primeira presencial. Paz, cuidado, servi\u00e7o, prote\u00e7\u00e3o, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/\" \/>\n<meta property=\"og:site_name\" content=\"United World Project\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-04T11:38:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T15:13:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2030-2048x1363-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1803\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"anita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/\"},\"author\":{\"name\":\"anita\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"headline\":\"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d\",\"datePublished\":\"2022-10-04T11:38:21+00:00\",\"dateModified\":\"2025-11-26T15:13:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/\"},\"wordCount\":840,\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_2030-2048x1363-1.jpg\",\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/\",\"name\":\"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d - United World Project\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_2030-2048x1363-1.jpg\",\"datePublished\":\"2022-10-04T11:38:21+00:00\",\"dateModified\":\"2025-11-26T15:13:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_2030-2048x1363-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unitedworldproject.org\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_2030-2048x1363-1.jpg\",\"width\":1803,\"height\":1200,\"caption\":\"Fonte: Diocesi Assisi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/economia-trabalho\\\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/\",\"name\":\"United World Project\",\"description\":\"Championing fraternity and collaboration worldwide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/#\\\/schema\\\/person\\\/5e422fc57d77d69e6b4e36ac59a53201\",\"name\":\"anita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g\",\"caption\":\"anita\"},\"url\":\"https:\\\/\\\/www.unitedworldproject.org\\\/pt-br\\\/author\\\/anita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d - United World Project","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/","og_locale":"pt_BR","og_type":"article","og_title":"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d - United World Project","og_description":"Por Lucia Capuzzi Em 24 de setembro de 2022, o Papa Francisco foi a Assis para se encontrar com os jovens economistas, empres\u00e1rios e agentes de transforma\u00e7\u00e3o da Economia de Francesco, que vieram de mais de 100 pa\u00edses ao redor do mundo para a terceira edi\u00e7\u00e3o do evento, a primeira presencial. Paz, cuidado, servi\u00e7o, prote\u00e7\u00e3o, [&hellip;]","og_url":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/","og_site_name":"United World Project","article_published_time":"2022-10-04T11:38:21+00:00","article_modified_time":"2025-11-26T15:13:35+00:00","og_image":[{"width":1803,"height":1200,"url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2030-2048x1363-1.jpg","type":"image\/jpeg"}],"author":"anita","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"anita","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/#article","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/"},"author":{"name":"anita","@id":"https:\/\/www.unitedworldproject.org\/pt-br\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"headline":"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d","datePublished":"2022-10-04T11:38:21+00:00","dateModified":"2025-11-26T15:13:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/"},"wordCount":840,"image":{"@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2030-2048x1363-1.jpg","inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/","url":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/","name":"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d - United World Project","isPartOf":{"@id":"https:\/\/www.unitedworldproject.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/#primaryimage"},"image":{"@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2030-2048x1363-1.jpg","datePublished":"2022-10-04T11:38:21+00:00","dateModified":"2025-11-26T15:13:35+00:00","author":{"@id":"https:\/\/www.unitedworldproject.org\/pt-br\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201"},"breadcrumb":{"@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/#primaryimage","url":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2030-2048x1363-1.jpg","contentUrl":"https:\/\/www.unitedworldproject.org\/wp-content\/uploads\/2025\/11\/IMG_2030-2048x1363-1.jpg","width":1803,"height":1200,"caption":"Fonte: Diocesi Assisi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unitedworldproject.org\/pt-br\/economia-trabalho\/papa-francisco-assina-o-pacto-com-os-jovens-uma-nova-economia-nao-e-utopia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unitedworldproject.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Papa Francisco assina o \u201cpacto\u201d com os jovens: \u201cuma nova economia n\u00e3o \u00e9 utopia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.unitedworldproject.org\/pt-br\/#website","url":"https:\/\/www.unitedworldproject.org\/pt-br\/","name":"United World Project","description":"Championing fraternity and collaboration worldwide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unitedworldproject.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.unitedworldproject.org\/pt-br\/#\/schema\/person\/5e422fc57d77d69e6b4e36ac59a53201","name":"anita","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6949a15dd913b50588eec00981bd52d8c6ac8351a258558d372496c670e4ff2c?s=96&d=mm&r=g","caption":"anita"},"url":"https:\/\/www.unitedworldproject.org\/pt-br\/author\/anita\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/posts\/73050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/comments?post=73050"}],"version-history":[{"count":1,"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/posts\/73050\/revisions"}],"predecessor-version":[{"id":73051,"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/posts\/73050\/revisions\/73051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/media\/68070"}],"wp:attachment":[{"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/media?parent=73050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/categories?post=73050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unitedworldproject.org\/pt-br\/wp-json\/wp\/v2\/tags?post=73050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}